{"id":2223,"date":"2019-01-10T16:25:10","date_gmt":"2019-01-10T16:25:10","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart-elementor\/demos\/?page_id=2223"},"modified":"2019-01-10T16:25:10","modified_gmt":"2019-01-10T16:25:10","slug":"home-base-light","status":"publish","type":"page","link":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/","title":{"rendered":"Home base-light"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2223\" class=\"elementor elementor-2223\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1427920 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"1427920\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80841\" data-id=\"80841\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7480106 elementor-widget elementor-widget-wd_slider\" data-id=\"7480106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<style>\n\t\t\t#slider-52 .woodmart-slide {\n\t\t\t\tmin-height: 495px;\n\t\t\t}\n\t\t\t\n\t\t\t@media (min-width: 1025px) {\n\t\t\t\t.browser-Internet #slider-52 .woodmart-slide {\n\t\t\t\t\theight: 495px;\n\t\t\t\t}\n\t\t\t}\n\n\t\t\t@media (max-width: 1024px) {\n\t\t\t\t#slider-52 .woodmart-slide {\n\t\t\t\t\tmin-height: 435px;\n\t\t\t\t}\n\t\t\t}\n\n\t\t\t@media (max-width: 767px) {\n\t\t\t\t#slider-52 .woodmart-slide {\n\t\t\t\t\tmin-height: 375px;\n\t\t\t\t}\n\t\t\t}\n\n\t\t\t\t\t\t\t\t\t#slide-2225.woodmart-loaded {\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t#slide-2225 {\n\t\t\t\t\t\tbackground-color:#f8f8f8;\t\t\t\t\t\t}\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t@media (max-width: 1024px) {\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t@media (max-width: 767px) {\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t#slide-2226.woodmart-loaded {\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t#slide-2226 {\n\t\t\t\t\t\tbackground-color:#f8f8f8;\t\t\t\t\t\t}\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t@media (max-width: 1024px) {\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t@media (max-width: 767px) {\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t#slide-2227.woodmart-loaded {\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t#slide-2227 {\n\t\t\t\t\t\tbackground-color:#f8f8f8;\t\t\t\t\t\t}\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t@media (max-width: 1024px) {\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t@media (max-width: 767px) {\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t<\/style>\t\t\t<div id=\"slider-52\" class=\"woodmart-slider-wrapper arrows-style-2 pagin-style-1 pagin-color-dark wd-section-stretch\"  data-owl-carousel data-speed=\"9000\" data-wrap=\"yes\" data-autoheight=\"yes\" data-hide_pagination_control=\"no\" data-hide_prev_next_buttons=\"no\" data-sliding_speed=\"900\" data-content_animation=\"1\" data-desktop=\"1\" data-tablet_landscape=\"1\" data-tablet=\"1\" data-mobile=\"1\" >\n\t\t\t\t<div class=\"owl-carousel woodmart-slider  owl-items-lg-1 owl-items-md-1 owl-items-sm-1 owl-items-xs-1\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"slide-2225\" class=\"woodmart-slide slide-valign-bottom slide-halign-center content-full-width slide-without-padding\">\n\t\t\t\t\t\t\t<div class=\"container woodmart-slide-container\">\n\t\t\t\t\t\t\t\t<div class=\"woodmart-slide-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>.elementor-2225 .elementor-element.elementor-element-4189165 > .elementor-container > .elementor-column > .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-bc-flex-widget .elementor-2225 .elementor-element.elementor-element-5454549.elementor-column .elementor-widget-wrap{align-items:center;}.elementor-2225 .elementor-element.elementor-element-5454549.elementor-column.elementor-element[data-element_type=\"column\"] > .elementor-widget-wrap.elementor-element-populated{align-content:center;align-items:center;}.elementor-2225 .elementor-element.elementor-element-5454549 > .elementor-element-populated{margin:0px 0px 0px 300px;--e-column-margin-right:0px;--e-column-margin-left:300px;padding:20px 30px 60px 30px;}.elementor-2225 .elementor-element.elementor-element-2054788 .title-after_title, .elementor-2225 .elementor-element.elementor-element-2054788 .title-subtitle, .elementor-2225 .elementor-element.elementor-element-2054788 .woodmart-title-container{max-width:90%;}.elementor-2225 .elementor-element.elementor-element-2054788 .title{font-size:53px;}.elementor-2225 .elementor-element.elementor-element-2054788 .title-after_title{font-size:15px;line-height:25px;}.elementor-2225 .elementor-element.elementor-element-7009251{text-align:start;}.elementor-2225 .elementor-element.elementor-element-5358286{font-size:28px;color:#83B735;}.elementor-2225 .elementor-element.elementor-element-5358286 .elementor-text-editor{max-width:100%;}.elementor-2225 .elementor-element.elementor-element-8132309{text-align:center;}@media(max-width:1024px){.elementor-2225 .elementor-element.elementor-element-5454549 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;padding:20px 20px 20px 20px;}.elementor-2225 .elementor-element.elementor-element-2054788 .title{font-size:42px;}.elementor-2225 .elementor-element.elementor-element-4986965 > .elementor-element-populated{padding:50px 0px 0px 0px;}}@media(min-width:768px){.elementor-2225 .elementor-element.elementor-element-5454549{width:59.098%;}.elementor-2225 .elementor-element.elementor-element-4986965{width:40.862%;}}@media(max-width:1024px) and (min-width:768px){.elementor-2225 .elementor-element.elementor-element-5454549{width:50%;}.elementor-2225 .elementor-element.elementor-element-4986965{width:50%;}}@media(max-width:767px){.elementor-2225 .elementor-element.elementor-element-5454549{width:100%;}.elementor-2225 .elementor-element.elementor-element-5454549 > .elementor-element-populated{padding:30px 20px 20px 20px;}.elementor-2225 .elementor-element.elementor-element-2054788 .title{font-size:40px;}.elementor-2225 .elementor-element.elementor-element-4986965{width:100%;}.elementor-2225 .elementor-element.elementor-element-4986965 > .elementor-element-populated{padding:30px 0px 0px 0px;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2225\" class=\"elementor elementor-2225\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4189165 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"4189165\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5454549\" data-id=\"5454549\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2054788 elementor-widget elementor-widget-wd_title\" data-id=\"2054788\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tSimple -<br \/>\nRock Chair.\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title\">\n\t\t\t\t\tSemper vulputate aliquam curae condimentum quisque gravida fusce convallis arcu cum at.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7009251 elementor-widget elementor-widget-image\" data-id=\"7009251\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"216\" height=\"47\" src=\"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2019\/01\/swatch-main-demo-light-slider.jpg\" class=\"attachment-full size-full wp-image-2236\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5358286 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"5358286\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>$199.00<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4986965\" data-id=\"4986965\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8132309 elementor-widget elementor-widget-image\" data-id=\"8132309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"541\" height=\"469\" src=\"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2019\/01\/slider-main-demo-1-light-blur.jpg\" class=\"attachment-full size-full wp-image-2232\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"slide-2226\" class=\"woodmart-slide slide-valign-bottom slide-halign-center content-full-width slide-without-padding\">\n\t\t\t\t\t\t\t<div class=\"container woodmart-slide-container\">\n\t\t\t\t\t\t\t\t<div class=\"woodmart-slide-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>.elementor-2226 .elementor-element.elementor-element-9869751 > .elementor-container > .elementor-column > .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-bc-flex-widget .elementor-2226 .elementor-element.elementor-element-5268630.elementor-column .elementor-widget-wrap{align-items:center;}.elementor-2226 .elementor-element.elementor-element-5268630.elementor-column.elementor-element[data-element_type=\"column\"] > .elementor-widget-wrap.elementor-element-populated{align-content:center;align-items:center;}.elementor-2226 .elementor-element.elementor-element-5268630 > .elementor-element-populated{margin:0px 0px 0px 300px;--e-column-margin-right:0px;--e-column-margin-left:300px;padding:20px 30px 60px 30px;}.elementor-2226 .elementor-element.elementor-element-9664169 .title-after_title, .elementor-2226 .elementor-element.elementor-element-9664169 .title-subtitle, .elementor-2226 .elementor-element.elementor-element-9664169 .woodmart-title-container{max-width:90%;}.elementor-2226 .elementor-element.elementor-element-9664169 .title{font-size:53px;}.elementor-2226 .elementor-element.elementor-element-9664169 .title-after_title{font-size:15px;line-height:25px;}.elementor-2226 .elementor-element.elementor-element-1324224{font-size:28px;color:#83B735;}.elementor-2226 .elementor-element.elementor-element-1324224 .elementor-text-editor{max-width:100%;}.elementor-2226 .elementor-element.elementor-element-9961548{text-align:center;}@media(max-width:1024px){.elementor-2226 .elementor-element.elementor-element-5268630 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;padding:20px 20px 20px 20px;}.elementor-2226 .elementor-element.elementor-element-9664169 .title-after_title, .elementor-2226 .elementor-element.elementor-element-9664169 .title-subtitle, .elementor-2226 .elementor-element.elementor-element-9664169 .woodmart-title-container{max-width:100%;}.elementor-2226 .elementor-element.elementor-element-9664169 .title{font-size:42px;}.elementor-2226 .elementor-element.elementor-element-1083112 > .elementor-element-populated{padding:50px 0px 0px 0px;}}@media(max-width:1024px) and (min-width:768px){.elementor-2226 .elementor-element.elementor-element-5268630{width:50%;}.elementor-2226 .elementor-element.elementor-element-1083112{width:50%;}}@media(max-width:767px){.elementor-2226 .elementor-element.elementor-element-5268630{width:100%;}.elementor-2226 .elementor-element.elementor-element-5268630 > .elementor-element-populated{padding:30px 20px 20px 20px;}.elementor-2226 .elementor-element.elementor-element-9664169 .title{font-size:40px;}.elementor-2226 .elementor-element.elementor-element-1083112{width:100%;}.elementor-2226 .elementor-element.elementor-element-1083112 > .elementor-element-populated{padding:30px 0px 0px 0px;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2226\" class=\"elementor elementor-2226\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9869751 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"9869751\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-60 elementor-top-column elementor-element elementor-element-5268630\" data-id=\"5268630\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9664169 elementor-widget elementor-widget-wd_title\" data-id=\"9664169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tEames -<br \/>\nSide Chair.\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title\">\n\t\t\t\t\tSemper vulputate aliquam curae condimentum quisque gravida fusce convallis arcu cum at.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1324224 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"1324224\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Only $99.00<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-40 elementor-top-column elementor-element elementor-element-1083112\" data-id=\"1083112\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9961548 elementor-widget elementor-widget-image\" data-id=\"9961548\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"410\" height=\"469\" src=\"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2019\/01\/slider-main-demo-2-light-blur.jpg\" class=\"attachment-full size-full wp-image-2233\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"slide-2227\" class=\"woodmart-slide slide-valign-middle slide-halign-center content-full-width slide-without-padding\">\n\t\t\t\t\t\t\t<div class=\"container woodmart-slide-container\">\n\t\t\t\t\t\t\t\t<div class=\"woodmart-slide-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>.elementor-2227 .elementor-element.elementor-element-418503 > .elementor-container > .elementor-column > .elementor-widget-wrap{align-content:center;align-items:center;}.elementor-2227 .elementor-element.elementor-element-4191229 > .elementor-element-populated{margin:0px 0px 0px 300px;--e-column-margin-right:0px;--e-column-margin-left:300px;padding:30px 30px 30px 30px;}.elementor-2227 .elementor-element.elementor-element-8569614 .title-after_title, .elementor-2227 .elementor-element.elementor-element-8569614 .title-subtitle, .elementor-2227 .elementor-element.elementor-element-8569614 .woodmart-title-container{max-width:100%;}.elementor-2227 .elementor-element.elementor-element-8569614 .title-subtitle{color:#777777;font-size:15px;font-weight:600;line-height:25px;}.elementor-2227 .elementor-element.elementor-element-8569614 .title{font-size:44px;}.elementor-2227 .elementor-element.elementor-element-8569614 .title-after_title{font-size:15px;line-height:25px;}.elementor-2227 .elementor-element.elementor-element-6742321{font-size:28px;color:#83B735;}.elementor-2227 .elementor-element.elementor-element-6742321 .elementor-text-editor{max-width:100%;}.elementor-2227 .elementor-element.elementor-element-5657977{text-align:center;}@media(max-width:1024px){.elementor-2227 .elementor-element.elementor-element-4191229 > .elementor-element-populated{margin:0px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;}.elementor-2227 .elementor-element.elementor-element-8569614 .title{font-size:40px;}.elementor-2227 .elementor-element.elementor-element-8569614 .title-after_title{font-size:15px;line-height:25px;}.elementor-2227 .elementor-element.elementor-element-2327706 > .elementor-element-populated{padding:30px 30px 30px 30px;}}@media(max-width:1024px) and (min-width:768px){.elementor-2227 .elementor-element.elementor-element-4191229{width:50%;}.elementor-2227 .elementor-element.elementor-element-2327706{width:50%;}}@media(max-width:767px){.elementor-2227 .elementor-element.elementor-element-4191229{width:100%;}.elementor-2227 .elementor-element.elementor-element-8569614 .title-after_title, .elementor-2227 .elementor-element.elementor-element-8569614 .title-subtitle, .elementor-2227 .elementor-element.elementor-element-8569614 .woodmart-title-container{max-width:100%;}.elementor-2227 .elementor-element.elementor-element-8569614 .title{font-size:38px;}.elementor-2227 .elementor-element.elementor-element-2327706{width:100%;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2227\" class=\"elementor elementor-2227\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-418503 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"418503\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-60 elementor-top-column elementor-element elementor-element-4191229\" data-id=\"4191229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8569614 elementor-widget elementor-widget-wd_title\" data-id=\"8569614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-default text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-style-default\">\n\t\t\t\t\tCAPPELLINI\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tWooden<br \/>\nLounge Chairs.\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title\">\n\t\t\t\t\tSemper vulputate aliquam curae entum quisque gravida fusce cum at.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6742321 text-center color-scheme-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6742321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>$999.00<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-40 elementor-top-column elementor-element elementor-element-2327706\" data-id=\"2327706\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5657977 elementor-widget elementor-widget-image\" data-id=\"5657977\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"471\" src=\"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2019\/01\/slider-main-demo-3-light-blur.jpg\" class=\"attachment-full size-full wp-image-2234\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-640604 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"640604\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6952217\" data-id=\"6952217\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6550552 elementor-widget elementor-widget-wd_title\" data-id=\"6550552\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-medium text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-style-default\">\n\t\t\t\t\tWOODMART COLLECTIONS\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tFEATURED CATEGORIES\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title\">\n\t\t\t\t\tWoodMart is a powerful eCommerce theme for WordPress.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-803321 wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"803321\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7396417\" data-id=\"7396417\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7353861 elementor-widget elementor-widget-wd_title\" data-id=\"7353861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-medium text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-style-default\">\n\t\t\t\t\tWOODEN ACCESSORIES\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tFEATURED PRODUCTS\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title\">\n\t\t\t\t\tVisit our shop to see amazing creations from our designers.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9873706 elementor-section-content-middle wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9873706\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7757980\" data-id=\"7757980\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7203122 elementor-widget elementor-widget-image\" data-id=\"7203122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"491\" src=\"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2017\/06\/wood-chair-1.png\" class=\"attachment-full size-full wp-image-416\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5696281\" data-id=\"5696281\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1794917 elementor-widget elementor-widget-wd_title\" data-id=\"1794917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-white woodmart-title-style-default woodmart-title-size-default text-left\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-style-default\">\n\t\t\t\t\tPRODUCT LANDING PAGE\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tVitra Chair -<br \/>\nClassic Design.\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8817700 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"8817700\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7826078\" data-id=\"7826078\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-476489 elementor-widget elementor-widget-wd_infobox\" data-id=\"476489\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-top box-style-base color-scheme-light box-title-small cursor-pointer\"onclick=\"window.location.href='#'\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title box-title-style-underlined\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tDESIGNER:\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p><em>Charles, Ray Eames<\/em><\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2a5af40\" data-id=\"2a5af40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6b5c27 elementor-widget elementor-widget-wd_infobox\" data-id=\"a6b5c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-top box-style-base color-scheme-light box-title-small cursor-pointer\"onclick=\"window.location.href='#'\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title box-title-style-underlined\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tMATERIALS:\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p><em>Wood, Leather, Metal<\/em><\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a2e8fb8\" data-id=\"a2e8fb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eccd532 elementor-widget elementor-widget-wd_infobox\" data-id=\"eccd532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-top box-style-base color-scheme-light box-title-small cursor-pointer\"onclick=\"window.location.href='#'\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title box-title-style-underlined\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tCLIENT:\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p><em>Woodmart, Basel<\/em><\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2944493 color-scheme-light elementor-widget__width-auto text-left elementor-widget elementor-widget-text-editor\" data-id=\"2944493\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>$1999.00<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9828594 elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"9828594\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"woodmart-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-bordered btn-shape-rectangle btn-size-default btn-color-white btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tADD TO CART\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8577119 wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8577119\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4846526\" data-id=\"4846526\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-561bcad color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"561bcad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ALL-IN-ONE ECOMMERCE SOLUTION<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5823458 elementor-widget elementor-widget-wd_title\" data-id=\"5823458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tABOUT OUR WOODMART STORE\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8802906 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"8802906\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nec \u00a0adipiscing luctus consequat penatibus parturient massa cubilia etiam a adipiscing enigm dignissim congue egestas sapien a. Scelerisque ac non ut ac bibendum himenaeos ullamcorper justo himenaeos vel a sapien quis.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3580319 elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"3580319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"woodmart-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-default btn-color-primary btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tRead More\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6474171 elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"6474171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"woodmart-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-bordered btn-shape-rectangle btn-size-default btn-color-default btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tContact us\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2502610 wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2502610\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7271295\" data-id=\"7271295\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2052127 elementor-widget elementor-widget-wd_title\" data-id=\"2052127\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-default text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\t<strong>JOIN OUR NEWSLETTER NOW<\/strong>\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-755309 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"755309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<\/p>\n<p style=\"text-align: center\">Will be used in accordance with our <a href=\"#\"><strong>Privacy Policy<\/strong><\/a><\/p>\n<p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2519772 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"2519772\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1977405\" data-id=\"1977405\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8255476 elementor-widget elementor-widget-wd_title\" data-id=\"8255476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-medium text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-style-default\">\n\t\t\t\t\tFURNITURE GUIDES\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tOUR LATEST NEWS\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title\">\n\t\t\t\t\tLatest trends and inspiration in interior design.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6931576 elementor-widget elementor-widget-wd_blog\" data-id=\"6931576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"carousel-785\"\n\t\t\t\t class=\"woodmart-carousel-container  slider-type-post woodmart-carousel-spacing-20 scroll-init\" data-owl-carousel data-speed=\"\" data-wrap=\"no\" data-hide_pagination_control=\"yes\" data-hide_prev_next_buttons=\"no\" data-desktop=\"3\" data-tablet_landscape=\"3\" data-tablet=\"2\" data-mobile=\"1\">\n\t\t\t\t\t\t\t\t<div class=\"owl-carousel owl-items-lg-3 owl-items-md-3 owl-items-sm-2 owl-items-xs-1\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"slide-post owl-carousel-item\">\n\t\t\t\n\t\t\t\t\t\t\t\n<article id=\"post-10527\" class=\"blog-post-loop post-slide blog-style-shadow blog-design-masonry post-10527 post type-post status-publish format-standard has-post-thumbnail hentry category-oficina\">\n\t<div class=\"article-inner\">\n\t\t<header class=\"entry-header\">\n\t\t\t\t\t\t\t<figure class=\"entry-thumbnail\">\n\t\t\t\t\t<div class=\"post-img-wrapp\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2025\/09\/12\/agradecimiento-a-nuestros-clientes\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-14.18.50-1.jpeg\" title=\"WhatsApp-Image-2025-09-10-at-14.18.50-1\" alt=\"WhatsApp-Image-2025-09-10-at-14.18.50-1\" loading=\"lazy\" \/>\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"post-image-mask\">\n\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/figure>\n\t\t\t\n\t\t\t\t\t\t<div class=\"post-date woodmart-post-date\" onclick=\"\">\n\t\t\t\t<span class=\"post-date-day\">\n\t\t\t\t\t12\t\t\t\t<\/span>\n\t\t\t\t<span class=\"post-date-month\">\n\t\t\t\t\tSep\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t<\/header><!-- .entry-header -->\n\n\t\t<div class=\"article-body-container\">\n\t\t\t\t\t\t\t<div class=\"meta-categories-wrapp\"><div class=\"meta-post-categories\"><a href=\"https:\/\/www.simonasesores.es\/index.php\/category\/oficina\/\" rel=\"category tag\">Oficina<\/a><\/div><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"entry-title title\">\n\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2025\/09\/12\/agradecimiento-a-nuestros-clientes\/\" rel=\"bookmark\">Agradecimiento a nuestros clientes<\/a>\n\t\t\t\t<\/h3>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-meta woodmart-entry-meta\">\n\t\t\t\t\t\t\t\t<ul class=\"entry-meta-list\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<li class=\"modified-date\"><time class=\"updated\" datetime=\"2025-10-07T07:53:00+00:00\">07\/10\/2025<\/time><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"meta-featured-post\">Featured<\/li>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"meta-author\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPosted by\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='author-avatar' src='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=32&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=64&#038;d=mm&#038;r=g 2x' class='avatar avatar-32 photo' height='32' width='32' \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/author\/simon\/\" rel=\"author\">\n\t\t\t\t\t\t\t\t<span class=\"vcard author author_name\">\n\t\t\t\t\t\t\t\t\t<span class=\"fn\">admin<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t\t\t\t\t\t<div class=\"hovered-social-icons\">\n\t\t\t\t\t\n\t\t\t<div class=\"woodmart-social-icons text-center icons-design-default icons-size-small color-scheme-light social-share social-form-circle\">\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.simonasesores.es\/index.php\/2025\/09\/12\/agradecimiento-a-nuestros-clientes\/\" target=\"_blank\" class=\" woodmart-social-icon social-facebook\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Facebook<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/www.simonasesores.es\/index.php\/2025\/09\/12\/agradecimiento-a-nuestros-clientes\/\" target=\"_blank\" class=\" woodmart-social-icon social-twitter\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Twitter<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.simonasesores.es\/index.php\/2025\/09\/12\/agradecimiento-a-nuestros-clientes\/\" target=\"_blank\" class=\" woodmart-social-icon social-linkedin\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">linkedin<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-content woodmart-entry-content\">\n\t\t\t\t\t\n<p class=\"read-more-section\"><a class=\"btn-read-more more-link\" href=\"https:\/\/www.simonasesores.es\/index.php\/2025\/09\/12\/agradecimiento-a-nuestros-clientes\/\">Leer m\u00e1s<\/a><\/p>\t\t\t\t<\/div><!-- .entry-content -->\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/article><!-- #post -->\n\n\t\t\t\t\t\n\t\t<\/div>\n\t\t\t\t<div class=\"slide-post owl-carousel-item\">\n\t\t\t\n\t\t\t\t\t\t\t\n<article id=\"post-10584\" class=\"blog-post-loop post-slide blog-style-shadow blog-design-masonry post-10584 post type-post status-publish format-standard hentry category-uncategorized\">\n\t<div class=\"article-inner\">\n\t\t<header class=\"entry-header\">\n\t\t\t\n\t\t\t\t\t\t<div class=\"post-date woodmart-post-date\" onclick=\"\">\n\t\t\t\t<span class=\"post-date-day\">\n\t\t\t\t\t23\t\t\t\t<\/span>\n\t\t\t\t<span class=\"post-date-month\">\n\t\t\t\t\tFeb\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t<\/header><!-- .entry-header -->\n\n\t\t<div class=\"article-body-container\">\n\t\t\t\t\t\t\t<div class=\"meta-categories-wrapp\"><div class=\"meta-post-categories\"><a href=\"https:\/\/www.simonasesores.es\/index.php\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a><\/div><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"entry-title title\">\n\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/23\/lo-bueno-se-comparte\/\" rel=\"bookmark\">LO BUENO SE COMPARTE<\/a>\n\t\t\t\t<\/h3>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-meta woodmart-entry-meta\">\n\t\t\t\t\t\t\t\t<ul class=\"entry-meta-list\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<li class=\"modified-date\"><time class=\"updated\" datetime=\"2026-02-23T08:22:43+00:00\">23\/02\/2026<\/time><\/li>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"meta-author\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPosted by\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='author-avatar' src='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=32&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=64&#038;d=mm&#038;r=g 2x' class='avatar avatar-32 photo' height='32' width='32' \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/author\/simon\/\" rel=\"author\">\n\t\t\t\t\t\t\t\t<span class=\"vcard author author_name\">\n\t\t\t\t\t\t\t\t\t<span class=\"fn\">admin<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span class=\"meta-reply\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/23\/lo-bueno-se-comparte\/#respond\"><span class=\"replies-count\">0<\/span> <span class=\"replies-count-label\">comments<\/span><\/a>\t\t\t\t\t\t<\/span><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t\t\t\t\t\t<div class=\"hovered-social-icons\">\n\t\t\t\t\t\n\t\t\t<div class=\"woodmart-social-icons text-center icons-design-default icons-size-small color-scheme-light social-share social-form-circle\">\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/23\/lo-bueno-se-comparte\/\" target=\"_blank\" class=\" woodmart-social-icon social-facebook\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Facebook<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/23\/lo-bueno-se-comparte\/\" target=\"_blank\" class=\" woodmart-social-icon social-twitter\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Twitter<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/23\/lo-bueno-se-comparte\/\" target=\"_blank\" class=\" woodmart-social-icon social-linkedin\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">linkedin<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-content woodmart-entry-content\">\n\t\t\t\t\t\nDel 01\/03\/2026 al 31\/12\/2026\n\n\n<p class=\"read-more-section\"><a class=\"btn-read-more more-link\" href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/23\/lo-bueno-se-comparte\/\">Leer m\u00e1s<\/a><\/p>\t\t\t\t<\/div><!-- .entry-content -->\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/article><!-- #post -->\n\n\t\t\t\t\t\n\t\t<\/div>\n\t\t\t\t<div class=\"slide-post owl-carousel-item\">\n\t\t\t\n\t\t\t\t\t\t\t\n<article id=\"post-10582\" class=\"blog-post-loop post-slide blog-style-shadow blog-design-masonry post-10582 post type-post status-publish format-standard hentry category-uncategorized\">\n\t<div class=\"article-inner\">\n\t\t<header class=\"entry-header\">\n\t\t\t\n\t\t\t\t\t\t<div class=\"post-date woodmart-post-date\" onclick=\"\">\n\t\t\t\t<span class=\"post-date-day\">\n\t\t\t\t\t13\t\t\t\t<\/span>\n\t\t\t\t<span class=\"post-date-month\">\n\t\t\t\t\tFeb\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t<\/header><!-- .entry-header -->\n\n\t\t<div class=\"article-body-container\">\n\t\t\t\t\t\t\t<div class=\"meta-categories-wrapp\"><div class=\"meta-post-categories\"><a href=\"https:\/\/www.simonasesores.es\/index.php\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a><\/div><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"entry-title title\">\n\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/13\/disfruta-de-tu-patin\/\" rel=\"bookmark\">DISFRUTA DE TU PATIN<\/a>\n\t\t\t\t<\/h3>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-meta woodmart-entry-meta\">\n\t\t\t\t\t\t\t\t<ul class=\"entry-meta-list\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<li class=\"modified-date\"><time class=\"updated\" datetime=\"2026-02-13T09:01:24+00:00\">13\/02\/2026<\/time><\/li>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"meta-author\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPosted by\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='author-avatar' src='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=32&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=64&#038;d=mm&#038;r=g 2x' class='avatar avatar-32 photo' height='32' width='32' \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/author\/simon\/\" rel=\"author\">\n\t\t\t\t\t\t\t\t<span class=\"vcard author author_name\">\n\t\t\t\t\t\t\t\t\t<span class=\"fn\">admin<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span class=\"meta-reply\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/13\/disfruta-de-tu-patin\/#respond\"><span class=\"replies-count\">0<\/span> <span class=\"replies-count-label\">comments<\/span><\/a>\t\t\t\t\t\t<\/span><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t\t\t\t\t\t<div class=\"hovered-social-icons\">\n\t\t\t\t\t\n\t\t\t<div class=\"woodmart-social-icons text-center icons-design-default icons-size-small color-scheme-light social-share social-form-circle\">\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/13\/disfruta-de-tu-patin\/\" target=\"_blank\" class=\" woodmart-social-icon social-facebook\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Facebook<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/13\/disfruta-de-tu-patin\/\" target=\"_blank\" class=\" woodmart-social-icon social-twitter\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Twitter<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/13\/disfruta-de-tu-patin\/\" target=\"_blank\" class=\" woodmart-social-icon social-linkedin\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">linkedin<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-content woodmart-entry-content\">\n\t\t\t\t\t<p class=\"read-more-section\"><a class=\"btn-read-more more-link\" href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/13\/disfruta-de-tu-patin\/\">Leer m\u00e1s<\/a><\/p>\t\t\t\t<\/div><!-- .entry-content -->\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/article><!-- #post -->\n\n\t\t\t\t\t\n\t\t<\/div>\n\t\t\t\t<div class=\"slide-post owl-carousel-item\">\n\t\t\t\n\t\t\t\t\t\t\t\n<article id=\"post-10579\" class=\"blog-post-loop post-slide blog-style-shadow blog-design-masonry post-10579 post type-post status-publish format-standard hentry category-uncategorized\">\n\t<div class=\"article-inner\">\n\t\t<header class=\"entry-header\">\n\t\t\t\n\t\t\t\t\t\t<div class=\"post-date woodmart-post-date\" onclick=\"\">\n\t\t\t\t<span class=\"post-date-day\">\n\t\t\t\t\t05\t\t\t\t<\/span>\n\t\t\t\t<span class=\"post-date-month\">\n\t\t\t\t\tFeb\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t<\/header><!-- .entry-header -->\n\n\t\t<div class=\"article-body-container\">\n\t\t\t\t\t\t\t<div class=\"meta-categories-wrapp\"><div class=\"meta-post-categories\"><a href=\"https:\/\/www.simonasesores.es\/index.php\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a><\/div><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"entry-title title\">\n\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/05\/50-x-50\/\" rel=\"bookmark\">50 X 50<\/a>\n\t\t\t\t<\/h3>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-meta woodmart-entry-meta\">\n\t\t\t\t\t\t\t\t<ul class=\"entry-meta-list\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<li class=\"modified-date\"><time class=\"updated\" datetime=\"2026-02-05T11:10:49+00:00\">05\/02\/2026<\/time><\/li>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"meta-author\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPosted by\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='author-avatar' src='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=32&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=64&#038;d=mm&#038;r=g 2x' class='avatar avatar-32 photo' height='32' width='32' \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/author\/simon\/\" rel=\"author\">\n\t\t\t\t\t\t\t\t<span class=\"vcard author author_name\">\n\t\t\t\t\t\t\t\t\t<span class=\"fn\">admin<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span class=\"meta-reply\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/05\/50-x-50\/#respond\"><span class=\"replies-count\">0<\/span> <span class=\"replies-count-label\">comments<\/span><\/a>\t\t\t\t\t\t<\/span><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t\t\t\t\t\t<div class=\"hovered-social-icons\">\n\t\t\t\t\t\n\t\t\t<div class=\"woodmart-social-icons text-center icons-design-default icons-size-small color-scheme-light social-share social-form-circle\">\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/05\/50-x-50\/\" target=\"_blank\" class=\" woodmart-social-icon social-facebook\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Facebook<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/05\/50-x-50\/\" target=\"_blank\" class=\" woodmart-social-icon social-twitter\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Twitter<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.simonasesores.es\/index.php\/2026\/02\/05\/50-x-50\/\" target=\"_blank\" class=\" woodmart-social-icon social-linkedin\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">linkedin<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-content woodmart-entry-content\">\n\t\t\t\t\t<p class=\"read-more-section\"><a class=\"btn-read-more more-link\" href=\"https:\/\/www.simonasesores.es\/index.php\/2026\/02\/05\/50-x-50\/\">Leer m\u00e1s<\/a><\/p>\t\t\t\t<\/div><!-- .entry-content -->\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/article><!-- #post -->\n\n\t\t\t\t\t\n\t\t<\/div>\n\t\t\t\t<div class=\"slide-post owl-carousel-item\">\n\t\t\t\n\t\t\t\t\t\t\t\n<article id=\"post-10571\" class=\"blog-post-loop post-slide blog-style-shadow blog-design-masonry post-10571 post type-post status-publish format-standard has-post-thumbnail hentry category-eventos\">\n\t<div class=\"article-inner\">\n\t\t<header class=\"entry-header\">\n\t\t\t\t\t\t\t<figure class=\"entry-thumbnail\">\n\t\t\t\t\t<div class=\"post-img-wrapp\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2025\/12\/03\/felicitaciones-navidad-2021-2024\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2025\/12\/Captura-de-pantalla-2025-12-03-a-las-11.23.05.png\" title=\"Captura de pantalla 2025-12-03 a las 11.23.05\" alt=\"Captura de pantalla 2025-12-03 a las 11.23.05\" loading=\"lazy\" \/>\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"post-image-mask\">\n\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/figure>\n\t\t\t\n\t\t\t\t\t\t<div class=\"post-date woodmart-post-date\" onclick=\"\">\n\t\t\t\t<span class=\"post-date-day\">\n\t\t\t\t\t03\t\t\t\t<\/span>\n\t\t\t\t<span class=\"post-date-month\">\n\t\t\t\t\tDic\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t<\/header><!-- .entry-header -->\n\n\t\t<div class=\"article-body-container\">\n\t\t\t\t\t\t\t<div class=\"meta-categories-wrapp\"><div class=\"meta-post-categories\"><a href=\"https:\/\/www.simonasesores.es\/index.php\/category\/eventos\/\" rel=\"category tag\">Eventos<\/a><\/div><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"entry-title title\">\n\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2025\/12\/03\/felicitaciones-navidad-2021-2024\/\" rel=\"bookmark\">Felicitaciones navidad 2021-2024<\/a>\n\t\t\t\t<\/h3>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-meta woodmart-entry-meta\">\n\t\t\t\t\t\t\t\t<ul class=\"entry-meta-list\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<li class=\"modified-date\"><time class=\"updated\" datetime=\"2025-12-03T10:31:07+00:00\">03\/12\/2025<\/time><\/li>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"meta-author\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPosted by\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='author-avatar' src='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=32&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/45408746d85c02b8403ae0c7ab8c4930907c40bb26d1c61425dc6db290bfaae3?s=64&#038;d=mm&#038;r=g 2x' class='avatar avatar-32 photo' height='32' width='32' \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/author\/simon\/\" rel=\"author\">\n\t\t\t\t\t\t\t\t<span class=\"vcard author author_name\">\n\t\t\t\t\t\t\t\t\t<span class=\"fn\">admin<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span class=\"meta-reply\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.simonasesores.es\/index.php\/2025\/12\/03\/felicitaciones-navidad-2021-2024\/#respond\"><span class=\"replies-count\">0<\/span> <span class=\"replies-count-label\">comments<\/span><\/a>\t\t\t\t\t\t<\/span><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t\t\t\t\t\t<div class=\"hovered-social-icons\">\n\t\t\t\t\t\n\t\t\t<div class=\"woodmart-social-icons text-center icons-design-default icons-size-small color-scheme-light social-share social-form-circle\">\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.simonasesores.es\/index.php\/2025\/12\/03\/felicitaciones-navidad-2021-2024\/\" target=\"_blank\" class=\" woodmart-social-icon social-facebook\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Facebook<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/www.simonasesores.es\/index.php\/2025\/12\/03\/felicitaciones-navidad-2021-2024\/\" target=\"_blank\" class=\" woodmart-social-icon social-twitter\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Twitter<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.simonasesores.es\/index.php\/2025\/12\/03\/felicitaciones-navidad-2021-2024\/\" target=\"_blank\" class=\" woodmart-social-icon social-linkedin\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">linkedin<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"entry-content woodmart-entry-content\">\n\t\t\t\t\t<p class=\"read-more-section\"><a class=\"btn-read-more more-link\" href=\"https:\/\/www.simonasesores.es\/index.php\/2025\/12\/03\/felicitaciones-navidad-2021-2024\/\">Leer m\u00e1s<\/a><\/p>\t\t\t\t<\/div><!-- .entry-content -->\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/article><!-- #post -->\n\n\t\t\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div> <!-- end product-items -->\n\t\t\t<\/div> <!-- end #carousel-785 -->\n\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3015571 wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3015571\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-115394\" data-id=\"115394\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>22 Jun Furniture Minimalist Japanese-inspired furniture June 22, 2017 Posted by admin 0 comments Facebook Twitter Pinterest linkedin Telegram Ac<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2223","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home base-light - Sim\u00f3n Asesores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home base-light - Sim\u00f3n Asesores\" \/>\n<meta property=\"og:description\" content=\"22 Jun Furniture Minimalist Japanese-inspired furniture June 22, 2017 Posted by admin 0 comments Facebook Twitter Pinterest linkedin Telegram Ac\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/\" \/>\n<meta property=\"og:site_name\" content=\"Sim\u00f3n Asesores\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dummy.xtemos.com\/woodmart-elementor\/demos\/wp-content\/uploads\/sites\/2\/2017\/06\/wood-blog-placeholder.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/\",\"name\":\"Home base-light - Sim\u00f3n Asesores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dummy.xtemos.com\\\/woodmart-elementor\\\/demos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/06\\\/wood-blog-placeholder.jpg\",\"datePublished\":\"2019-01-10T16:25:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dummy.xtemos.com\\\/woodmart-elementor\\\/demos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/06\\\/wood-blog-placeholder.jpg\",\"contentUrl\":\"http:\\\/\\\/dummy.xtemos.com\\\/woodmart-elementor\\\/demos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/06\\\/wood-blog-placeholder.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/home-base-light\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.simonasesores.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home base-light\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#website\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/\",\"name\":\"Sim\u00f3n Asesores\",\"description\":\"Asesores de seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.simonasesores.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#organization\",\"name\":\"Sim\u00f3n Asesores\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1531986130207.jpg\",\"contentUrl\":\"https:\\\/\\\/www.simonasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1531986130207.jpg\",\"width\":1250,\"height\":645,\"caption\":\"Sim\u00f3n Asesores\"},\"image\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home base-light - Sim\u00f3n Asesores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/","og_locale":"es_ES","og_type":"article","og_title":"Home base-light - Sim\u00f3n Asesores","og_description":"22 Jun Furniture Minimalist Japanese-inspired furniture June 22, 2017 Posted by admin 0 comments Facebook Twitter Pinterest linkedin Telegram Ac","og_url":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/","og_site_name":"Sim\u00f3n Asesores","og_image":[{"url":"http:\/\/dummy.xtemos.com\/woodmart-elementor\/demos\/wp-content\/uploads\/sites\/2\/2017\/06\/wood-blog-placeholder.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/","url":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/","name":"Home base-light - Sim\u00f3n Asesores","isPartOf":{"@id":"https:\/\/www.simonasesores.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/#primaryimage"},"image":{"@id":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/#primaryimage"},"thumbnailUrl":"http:\/\/dummy.xtemos.com\/woodmart-elementor\/demos\/wp-content\/uploads\/sites\/2\/2017\/06\/wood-blog-placeholder.jpg","datePublished":"2019-01-10T16:25:10+00:00","breadcrumb":{"@id":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.simonasesores.es\/index.php\/home-base-light\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/#primaryimage","url":"http:\/\/dummy.xtemos.com\/woodmart-elementor\/demos\/wp-content\/uploads\/sites\/2\/2017\/06\/wood-blog-placeholder.jpg","contentUrl":"http:\/\/dummy.xtemos.com\/woodmart-elementor\/demos\/wp-content\/uploads\/sites\/2\/2017\/06\/wood-blog-placeholder.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.simonasesores.es\/index.php\/home-base-light\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.simonasesores.es\/"},{"@type":"ListItem","position":2,"name":"Home base-light"}]},{"@type":"WebSite","@id":"https:\/\/www.simonasesores.es\/#website","url":"https:\/\/www.simonasesores.es\/","name":"Sim\u00f3n Asesores","description":"Asesores de seguros","publisher":{"@id":"https:\/\/www.simonasesores.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.simonasesores.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.simonasesores.es\/#organization","name":"Sim\u00f3n Asesores","url":"https:\/\/www.simonasesores.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.simonasesores.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2022\/07\/1531986130207.jpg","contentUrl":"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2022\/07\/1531986130207.jpg","width":1250,"height":645,"caption":"Sim\u00f3n Asesores"},"image":{"@id":"https:\/\/www.simonasesores.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/pages\/2223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/comments?post=2223"}],"version-history":[{"count":0,"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/pages\/2223\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/media?parent=2223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}