{"id":655,"date":"2017-06-27T06:32:31","date_gmt":"2017-06-27T06:32:31","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart-elementor\/demos\/?page_id=655"},"modified":"2017-06-27T06:32:31","modified_gmt":"2017-06-27T06:32:31","slug":"contact-us-4","status":"publish","type":"page","link":"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/","title":{"rendered":"Contact Us 4"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"655\" class=\"elementor elementor-655\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9382255 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"9382255\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-992168\" data-id=\"992168\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3734264 elementor-widget elementor-widget-wd_title\" data-id=\"3734264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tOUR ADDRESS\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4088235 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"4088235\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1665321\" data-id=\"1665321\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f3bf94 elementor-widget elementor-widget-wd_infobox\" data-id=\"4f3bf94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-top box-style-base color-scheme- box-title-default\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title box-title-style-default\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tNew York\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>56 E. Fieldstone Street<br \/>Summerville, SC 29483<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5982861 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"5982861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333\"><strong>Email:<\/strong><\/span>\u00a0 xtemos@gmail.com<br \/>\n<span style=\"color: #333333\"><strong>Phone:<\/strong><\/span>\u00a0 +18 (0) 545 77\u00a032<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4516340\" data-id=\"4516340\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42248f1 elementor-widget elementor-widget-wd_infobox\" data-id=\"42248f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-top box-style-base color-scheme- box-title-default\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title box-title-style-default\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tParis\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>28 Boulevard des<br \/>Capucines, 75009<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5852436 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"5852436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333\"><strong>Email:<\/strong><\/span>\u00a0 xtemos@gmail.com<br \/>\n<span style=\"color: #333333\"><strong>Phone:<\/strong><\/span>\u00a0 +18 (0) 545 77\u00a032<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9797615 elementor-widget elementor-widget-wd_title\" data-id=\"9797615\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tCONTACT US\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8369153 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"8369153\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left\">Whether you\u2019re looking for answers, would like to solve a problem, or just want to let us know how we did, you\u2019ll find.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6621749 elementor-widget elementor-widget-wd_popup\" data-id=\"6621749\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"woodmart-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-default woodmart-open-popup btn-color-primary btn-icon-pos-right\"  href=\"#contact-form-popup\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tWRITE A MESSAGE\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"contact-form-popup\" class=\"mfp-with-anim woodmart-content-popup mfp-hide\" style=\"max-width:900px;\">\n\t\t\t\t<div class=\"woodmart-popup-inner\">\n\t\t\t\t\t<style>.elementor-317 .elementor-element.elementor-element-cff2778{margin:-30px -30px -30px -30px;}.elementor-317 .elementor-element.elementor-element-37d22ca > .elementor-element-populated{padding:30px 30px 15px 40px;}.elementor-317 .elementor-element.elementor-element-f13e6c1:not(.elementor-motion-effects-element-type-background) > .elementor-widget-wrap, .elementor-317 .elementor-element.elementor-element-f13e6c1 > .elementor-widget-wrap > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#333333;}.elementor-317 .elementor-element.elementor-element-f13e6c1 > .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;padding:30px 30px 30px 30px;}.elementor-317 .elementor-element.elementor-element-f13e6c1 > .elementor-element-populated > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-317 .elementor-element.elementor-element-aae0986 .info-box-inner{color:rgba(255, 255, 255, 0.8);}.elementor-317 .elementor-element.elementor-element-8424fc0 .info-box-inner{color:rgba(255, 255, 255, 0.8);}.elementor-317 .elementor-element.elementor-element-f4755d4 .info-box-inner{color:rgba(255, 255, 255, 0.8);}.elementor-317 .elementor-element.elementor-element-f3e7706{--divider-border-style:solid;--divider-color:rgba(255, 255, 255, 0.15);--divider-border-width:1px;}.elementor-317 .elementor-element.elementor-element-f3e7706 .elementor-divider-separator{width:100%;}.elementor-317 .elementor-element.elementor-element-f3e7706 .elementor-divider{padding-block-start:15px;padding-block-end:15px;}@media(max-width:1024px){.elementor-317 .elementor-element.elementor-element-37d22ca > .elementor-element-populated{padding:30px 30px 15px 30px;}}@media(min-width:768px){.elementor-317 .elementor-element.elementor-element-37d22ca{width:66.981%;}.elementor-317 .elementor-element.elementor-element-f13e6c1{width:32.98%;}}@media(max-width:1024px) and (min-width:768px){.elementor-317 .elementor-element.elementor-element-37d22ca{width:100%;}.elementor-317 .elementor-element.elementor-element-f13e6c1{width:100%;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"317\" class=\"elementor elementor-317\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cff2778 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"cff2778\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37d22ca\" data-id=\"37d22ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08c68c4 elementor-widget elementor-widget-wd_title\" data-id=\"08c68c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-default woodmart-title-style-default woodmart-title-size-small text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tSEND US A MESSAGE\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faeed27 elementor-widget elementor-widget-wd_contact_form_7\" data-id=\"faeed27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f331-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"331\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/655#wpcf7-f331-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"331\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f331-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Your Name<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Your Email<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Phone Number<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Company<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><label>Your Message<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"ASK A QUESTION\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"182\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f13e6c1\" data-id=\"f13e6c1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e75e20 elementor-widget elementor-widget-wd_title\" data-id=\"0e75e20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper woodmart-title-color-white woodmart-title-style-default woodmart-title-size-small text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"left-line\"><\/span>\n\n\t\t\t\t<h4 class=\"woodmart-title-container title\">\n\t\t\t\t\tCONTACT INFORMATION\t\t\t\t<\/h4>\n\n\t\t\t\t\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aae0986 elementor-widget elementor-widget-wd_infobox\" data-id=\"aae0986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-left box-style-base color-scheme- box-title-default cursor-pointer\"onclick=\"window.location.href='#'\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/dummy.xtemos.com\/woodmart-elementor\/wp-content\/uploads\/2017\/06\/chair.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>50 East 52nd Street<br \/>Brooklyn, NY 10022<br \/>United States<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8424fc0 elementor-widget elementor-widget-wd_infobox\" data-id=\"8424fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-left box-style-base color-scheme- box-title-default cursor-pointer\"onclick=\"window.location.href='#'\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/dummy.xtemos.com\/woodmart-elementor\/wp-content\/uploads\/2017\/06\/chair.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>+1322224332<br \/>+4643758533<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4755d4 elementor-widget elementor-widget-wd_infobox\" data-id=\"f4755d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"woodmart-info-box text-left box-icon-align-left box-style-base color-scheme- box-title-default cursor-pointer\"onclick=\"window.location.href='#'\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/dummy.xtemos.com\/woodmart-elementor\/wp-content\/uploads\/2017\/06\/chair.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-mb-10\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>info@google.com<br \/>support@google.com<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3e7706 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f3e7706\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62fc520 color-scheme-light text-left elementor-widget elementor-widget-text-editor\" data-id=\"62fc520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Do you have questions about how we can help your company? Send us an email and we\u2019ll get in touch shortly.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b567be4 elementor-widget elementor-widget-wd_social_buttons\" data-id=\"b567be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_social_buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"woodmart-social-icons text-left icons-design-colored icons-size-small color-scheme-dark social-share social-form-circle\">\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/\" target=\"_blank\" class=\" woodmart-social-icon social-facebook\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Facebook<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/\" target=\"_blank\" class=\" woodmart-social-icon social-twitter\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">Twitter<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/\" target=\"_blank\" class=\" woodmart-social-icon social-linkedin\">\n\t\t\t\t\t\t<i><\/i>\n\t\t\t\t\t\t<span class=\"woodmart-social-icon-name\">linkedin<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1221022\" data-id=\"1221022\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1394146 elementor-widget elementor-widget-wd_google_map\" data-id=\"1394146\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_google_map.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"google-map-container content-vertical-top content-horizontal-left\" data-map-args='{\"latitude\":\"48.87146\",\"longitude\":\"2.35500\",\"zoom\":15,\"mouse_zoom\":\"no\",\"init_type\":\"page_load\",\"init_offset\":null,\"json_style\":\"\",\"marker_icon\":\"https:\\\/\\\/www.simonasesores.es\\\/wp-content\\\/themes\\\/woodmart\\\/inc\\\/admin\\\/assets\\\/images\\\/google-icon.png\",\"elementor\":true,\"marker_text_needed\":\"no\",\"marker_text\":\"<h3 style=\\\"min-width:300px; text-align:center; margin:15px;\\\"><\\\/h3>\",\"selector\":\"woodmart-map-id-6a04ba99e6a90\"}'>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t<div class=\"woodmart-google-map-wrapper\">\n\t\t\t\t<div id=\"woodmart-map-id-6a04ba99e6a90\" class=\"woodmart-google-map without-content\"><\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>OUR ADDRESS New York 56 E. Fieldstone StreetSummerville, SC 29483 Email:\u00a0 xtemos@gmail.com Phone:\u00a0 +18 (0) 545 77\u00a032 Paris 28 Boulevard<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-655","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Us 4 - Sim\u00f3n Asesores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us 4 - Sim\u00f3n Asesores\" \/>\n<meta property=\"og:description\" content=\"OUR ADDRESS New York 56 E. Fieldstone StreetSummerville, SC 29483 Email:\u00a0 xtemos@gmail.com Phone:\u00a0 +18 (0) 545 77\u00a032 Paris 28 Boulevard\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Sim\u00f3n Asesores\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/contact-us-4\\\/\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/contact-us-4\\\/\",\"name\":\"Contact Us 4 - Sim\u00f3n Asesores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#website\"},\"datePublished\":\"2017-06-27T06:32:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/contact-us-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/contact-us-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/index.php\\\/contact-us-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.simonasesores.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Us 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#website\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/\",\"name\":\"Sim\u00f3n Asesores\",\"description\":\"Asesores de seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.simonasesores.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#organization\",\"name\":\"Sim\u00f3n Asesores\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.simonasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1531986130207.jpg\",\"contentUrl\":\"https:\\\/\\\/www.simonasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1531986130207.jpg\",\"width\":1250,\"height\":645,\"caption\":\"Sim\u00f3n Asesores\"},\"image\":{\"@id\":\"https:\\\/\\\/www.simonasesores.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us 4 - Sim\u00f3n Asesores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/","og_locale":"es_ES","og_type":"article","og_title":"Contact Us 4 - Sim\u00f3n Asesores","og_description":"OUR ADDRESS New York 56 E. Fieldstone StreetSummerville, SC 29483 Email:\u00a0 xtemos@gmail.com Phone:\u00a0 +18 (0) 545 77\u00a032 Paris 28 Boulevard","og_url":"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/","og_site_name":"Sim\u00f3n Asesores","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/","url":"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/","name":"Contact Us 4 - Sim\u00f3n Asesores","isPartOf":{"@id":"https:\/\/www.simonasesores.es\/#website"},"datePublished":"2017-06-27T06:32:31+00:00","breadcrumb":{"@id":"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.simonasesores.es\/index.php\/contact-us-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.simonasesores.es\/"},{"@type":"ListItem","position":2,"name":"Contact Us 4"}]},{"@type":"WebSite","@id":"https:\/\/www.simonasesores.es\/#website","url":"https:\/\/www.simonasesores.es\/","name":"Sim\u00f3n Asesores","description":"Asesores de seguros","publisher":{"@id":"https:\/\/www.simonasesores.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.simonasesores.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.simonasesores.es\/#organization","name":"Sim\u00f3n Asesores","url":"https:\/\/www.simonasesores.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.simonasesores.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2022\/07\/1531986130207.jpg","contentUrl":"https:\/\/www.simonasesores.es\/wp-content\/uploads\/2022\/07\/1531986130207.jpg","width":1250,"height":645,"caption":"Sim\u00f3n Asesores"},"image":{"@id":"https:\/\/www.simonasesores.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/pages\/655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/comments?post=655"}],"version-history":[{"count":0,"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/pages\/655\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.simonasesores.es\/index.php\/wp-json\/wp\/v2\/media?parent=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}